{"id":10,"date":"2026-02-23T19:52:44","date_gmt":"2026-02-23T18:52:44","guid":{"rendered":"https:\/\/themedicaltribune.com\/pt\/sponsoring\/"},"modified":"2026-02-23T19:52:44","modified_gmt":"2026-02-23T18:52:44","slug":"sponsoring","status":"publish","type":"page","link":"https:\/\/themedicaltribune.com\/pt\/sponsoring\/","title":{"rendered":"Sponsoring"},"content":{"rendered":"<div class=\"container\">\n<h1>Sponsoring<\/h1>\n<p><strong>Version de r\u00e9f\u00e9rence :<\/strong> Fran\u00e7aise (FR)<\/p>\n<p><strong>Derni\u00e8re mise \u00e0 jour :<\/strong> 02\/02\/2026<\/p>\n<p>Conform\u00e9ment \u00e0 l&#8217;article 20 de la LCEN (loi n\u00b0 2004-575 du 21 juin 2004), au Code de la consommation, aux recommandations de l&#8217;ARPP (Autorit\u00e9 de R\u00e9gulation Professionnelle de la Publicit\u00e9) et \u00e0 la Charte de d\u00e9ontologie de la presse en ligne, toute campagne de sponsoring avec <strong>The Medical Tribune<\/strong> est encadr\u00e9e par les conditions g\u00e9n\u00e9rales suivantes.<\/p>\n<p>Un contrat sp\u00e9cifique sera \u00e9tabli pour chaque campagne, compl\u00e9tant les pr\u00e9sentes dispositions g\u00e9n\u00e9rales.<\/p>\n<h2>1. Distinction stricte des contenus<\/h2>\n<p><strong>Obligation l\u00e9gale de transparence :<\/strong> une distinction claire et apparente est op\u00e9r\u00e9e entre les contenus \u00e9ditoriaux ind\u00e9pendants et les espaces publicitaires\/sponsoris\u00e9s.<\/p>\n<h3>1.1 Mentions obligatoires<\/h3>\n<p>Tout contenu sponsoris\u00e9 sera explicitement identifi\u00e9 par au moins une des mentions suivantes, plac\u00e9es de mani\u00e8re visible (titre, chapeau, ou en haut de l&#8217;article) :<\/p>\n<ul>\n<li>\u00ab Sponsoris\u00e9 par [Nom du sponsor] \u00bb<\/li>\n<li>\u00ab Article en partenariat avec [Nom du sponsor] \u00bb<\/li>\n<li>\u00ab Publicit\u00e9 \u00bb ou \u00ab Pub \u00bb<\/li>\n<li>\u00ab Contenu commercial \u00bb<\/li>\n<\/ul>\n<h3>1.2 Formats possibles<\/h3>\n<ul>\n<li>Encarts publicitaires (banni\u00e8res, native ads)<\/li>\n<li>Espace d\u00e9di\u00e9<\/li>\n<li>Prestation de service<\/li>\n<\/ul>\n<h2>2. Absence de Droit de Regard \u2013 Ind\u00e9pendance \u00e9ditoriale absolue<\/h2>\n<p>Le sponsor reconna\u00eet que sa participation financi\u00e8re ne lui conf\u00e8re aucun privil\u00e8ge :<\/p>\n<ul>\n<li>Aucune censure sur les contenus \u00e9ditoriaux du m\u00e9dia<\/li>\n<li>Aucun droit d&#8217;orientation sur les sujets trait\u00e9s par la r\u00e9daction<\/li>\n<li>Aucune modification des articles ou enqu\u00eates ind\u00e9pendantes<\/li>\n<\/ul>\n<p>La Direction de la r\u00e9daction conserve l&#8217;enti\u00e8re souverainet\u00e9 sur :<\/p>\n<ul>\n<li>Le traitement journalistique<\/li>\n<li>Le calendrier \u00e9ditorial<\/li>\n<li>Le ton et la forme des publications<\/li>\n<\/ul>\n<h2>3. Responsabilit\u00e9s contractuelles<\/h2>\n<h3>3.1 Obligations du Sponsor<\/h3>\n<p>Le sponsor s&#8217;engage \u00e0 :<\/p>\n<ul>\n<li>Fournir des contenus conformes \u00e0 la loi (absence de fausses informations, contenus illicites, discriminatoires, etc.)<\/li>\n<li>Respecter les d\u00e9lais de fourniture des \u00e9l\u00e9ments (textes, visuels, liens)<\/li>\n<li>Assumer la responsabilit\u00e9 exclusive des informations diffus\u00e9es dans son espace sponsoris\u00e9<\/li>\n<li>Respecter le RGPD pour tout traitement de donn\u00e9es personnelles qu&#8217;il initie<\/li>\n<\/ul>\n<h3>3.2 Obligations de The Medical Tribune<\/h3>\n<p><strong>The Medical Tribune<\/strong> :<\/p>\n<ul>\n<li>publie les contenus dans les d\u00e9lais convenus entre les parties.<\/li>\n<li>respecte l\u2019ensemble des engagements techniques relatifs aux formats, emplacements et dur\u00e9e d\u2019affichage des contenus.<\/li>\n<li>exerce une mod\u00e9ration \u00e9ditoriale sur les contenus sponsoris\u00e9s et dispose du droit de les refuser ou de les modifier si ceux-ci sont non conformes aux lois en vigueur ou \u00e0 la ligne \u00e9ditoriale.<\/li>\n<\/ul>\n<h2>4. Clause de R\u00e9siliation Imm\u00e9diate<\/h2>\n<p>Rupture automatique et unilat\u00e9rale du contrat de sponsoring, sans pr\u00e9avis ni indemnit\u00e9, en cas de :<\/p>\n<ul>\n<li>Pression exerc\u00e9e pour influencer les contenus \u00e9ditoriaux ind\u00e9pendants<\/li>\n<li>Non-respect des obligations l\u00e9gales (LCEN, ARPP, RGPD)<\/li>\n<li>Contenus sponsoris\u00e9s illicites ou portant atteinte \u00e0 la r\u00e9putation du m\u00e9dia<\/li>\n<li>Non-paiement des engagements financiers convenus<\/li>\n<\/ul>\n<h2>5. Donn\u00e9es personnelles et RGPD<\/h2>\n<p>Les donn\u00e9es trait\u00e9es dans le cadre du sponsoring (coordonn\u00e9es du contact sponsor, statistiques de performance, donn\u00e9es d&#8217;audience) sont couvertes par notre Politique de Confidentialit\u00e9, conforme au RGPD.<\/p>\n<p>Le sponsor agit en tant que responsable de traitement ind\u00e9pendant pour les donn\u00e9es qu&#8217;il collecte via ses espaces (pixels de tracking, formulaires, etc.) et doit respecter le RGPD.<\/p>\n<h2>6. Propri\u00e9t\u00e9 intellectuelle<\/h2>\n<p>Les contenus \u00e9ditoriaux restent la propri\u00e9t\u00e9 exclusive de <strong>The Medical Tribune<\/strong>.<\/p>\n<p>Les contenus fournis par le sponsor font l&#8217;objet d&#8217;une licence d&#8217;utilisation limit\u00e9e au m\u00e9dia pour la dur\u00e9e de la campagne.<\/p>\n<p>Toute r\u00e9utilisation des contenus sponsoris\u00e9s par le sponsor sur d&#8217;autres supports n\u00e9cessite l&#8217;accord pr\u00e9alable \u00e9crit.<\/p>\n<h2>7. Droit applicable et r\u00e8glement des litiges<\/h2>\n<p>Droit fran\u00e7ais exclusivement.<\/p>\n<p>En cas de litige relatif \u00e0 une campagne sp\u00e9cifique :<\/p>\n<ul>\n<li>Tentative de r\u00e8glement amiable dans un d\u00e9lai de 30 jours<\/li>\n<li>\u00c0 d\u00e9faut, comp\u00e9tence exclusive des tribunaux de <strong>Paris<\/strong>.<\/li>\n<\/ul>\n<h2>8. Clause de primaut\u00e9 de la version fran\u00e7aise<\/h2>\n<p>Les pr\u00e9sentes conditions sont disponibles en plus de 100 langues via traduction automatique. En cas de divergence ou d&#8217;erreur de traduction, seule la version fran\u00e7aise fait foi et est juridiquement opposable.<\/p>\n<h2>9. Proc\u00e9dure de demande de sponsoring<\/h2>\n<p>Premi\u00e8re d\u00e9marche obligatoire via le formulaire ci-dessous.<\/p>\n<p>Informations requises :<\/p>\n<ul>\n<li>Nom \/ Raison sociale<\/li>\n<li>Coordonn\u00e9es (email, t\u00e9l\u00e9phone)<\/li>\n<li>Type de sponsoring souhait\u00e9 (article, banni\u00e8re, espace d\u00e9di\u00e9)<\/li>\n<li>Budget \/ Dur\u00e9e envisag\u00e9s<\/li>\n<li>Description du projet<\/li>\n<\/ul>\n<p>Votre demande sera examin\u00e9e par notre Direction Commerciale. En cas d&#8217;int\u00e9r\u00eat, un contrat sp\u00e9cifique vous sera propos\u00e9 pr\u00e9cisant :<\/p>\n<ul>\n<li>Contenu et format de la campagne<\/li>\n<li>Tarification et modalit\u00e9s de paiement<\/li>\n<li>Planning d&#8217;ex\u00e9cution<\/li>\n<li>Conditions de r\u00e9siliation sp\u00e9cifiques<\/li>\n<\/ul>\n<div class=\"wlr-cf-wrapper wlr-cf-sponsoring\"\r\n          data-form-type=\"sponsoring\"\r\n     data-lang=\"pt\">\r\n\r\n    <!-- Message de retour (succ\u00e8s \/ erreur) -->\r\n    <div class=\"wlr-cf-response\" role=\"alert\" aria-live=\"polite\" aria-atomic=\"true\" style=\"display:none;\"><\/div>\r\n\r\n    <form\r\n        class=\"wlr-cf-form\"\r\n        id=\"wlr-form-sponsoring-285\"\r\n        method=\"post\"\r\n        action=\"https:\/\/themedicaltribune.com\/pt\/wp-admin\/admin-ajax.php\"\r\n        novalidate\r\n        autocomplete=\"on\"\r\n    >\r\n        <!-- Champs cach\u00e9s obligatoires -->\r\n        <input type=\"hidden\" name=\"action\"    value=\"wlr_cf_submit\">\r\n        <input type=\"hidden\" name=\"form_type\" value=\"sponsoring\">\r\n        <input type=\"hidden\" name=\"wlr_cf_nonce\" id=\"wlr-form-sponsoring-285_nonce\"\r\n               value=\"eea40efe92\">\r\n\r\n        <div class=\"wlr-cf-hp\" aria-hidden=\"true\" tabindex=\"-1\" style=\"position:absolute;left:-9999px;width:1px;height:1px;overflow:hidden;\"><label for=\"wlr_ebab7969\">Ne pas remplir<\/label><input type=\"text\" id=\"wlr_ebab7969\" name=\"wlr_ebab7969\" value=\"\" autocomplete=\"off\" tabindex=\"-1\"><\/div><div class=\"wlr-cf-field wlr-cf-field--text\" data-field=\"nom\"><label for=\"wlr-form-sponsoring-285_nom\">Nome completo <span class=\"wlr-cf-required\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wlr-form-sponsoring-285_nom\" name=\"nom\" placeholder=\"Seu nome e sobrenome\" autocomplete=\"off\" required aria-required=\"true\" class=\"wlr-cf-input\"><span class=\"wlr-cf-field-error\" role=\"alert\" aria-live=\"polite\"><\/span><\/div><div class=\"wlr-cf-field wlr-cf-field--email\" data-field=\"email\"><label for=\"wlr-form-sponsoring-285_email\">Endere\u00e7o de e-mail <span class=\"wlr-cf-required\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wlr-form-sponsoring-285_email\" name=\"email\" placeholder=\"voce@email.com\" autocomplete=\"email\" required aria-required=\"true\" class=\"wlr-cf-input\"><span class=\"wlr-cf-field-error\" role=\"alert\" aria-live=\"polite\"><\/span><\/div><div class=\"wlr-cf-field wlr-cf-field--text\" data-field=\"societe\"><label for=\"wlr-form-sponsoring-285_societe\">Empresa <span class=\"wlr-cf-required\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wlr-form-sponsoring-285_societe\" name=\"societe\" placeholder=\"Nome da sua empresa ou marca\" autocomplete=\"off\" required aria-required=\"true\" class=\"wlr-cf-input\"><span class=\"wlr-cf-field-error\" role=\"alert\" aria-live=\"polite\"><\/span><\/div><div class=\"wlr-cf-field wlr-cf-field--text\" data-field=\"budget\"><label for=\"wlr-form-sponsoring-285_budget\">Or\u00e7amento estimado<\/label><input type=\"text\" id=\"wlr-form-sponsoring-285_budget\" name=\"budget\" placeholder=\"Ex. 2000 BRL\" autocomplete=\"off\" class=\"wlr-cf-input\"><small class=\"wlr-cf-help\">Indique um intervalo se poss\u00edvel.<\/small><span class=\"wlr-cf-field-error\" role=\"alert\" aria-live=\"polite\"><\/span><\/div><div class=\"wlr-cf-field wlr-cf-field--textarea\" data-field=\"message\"><label for=\"wlr-form-sponsoring-285_message\">Vis\u00e3o geral do projeto <span class=\"wlr-cf-required\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wlr-form-sponsoring-285_message\" name=\"message\" placeholder=\"Descreva sua oferta e objetivos\u2026\" rows=\"5\" required aria-required=\"true\" class=\"wlr-cf-input wlr-cf-textarea\"><\/textarea><span class=\"wlr-cf-field-error\" role=\"alert\" aria-live=\"polite\"><\/span><\/div><div class=\"wlr-cf-math-challenge\">\r\n                <label for=\"wlr_math_answer\">Verifica\u00e7\u00e3o: <strong>7 + 6 = ?<\/strong><\/label>\r\n                <input type=\"number\" id=\"wlr_math_answer\" name=\"wlr_math_answer\"\r\n                       min=\"1\" max=\"18\" required autocomplete=\"off\"\r\n                       placeholder=\"Sua resposta\" aria-required=\"true\">\r\n                <input type=\"hidden\" name=\"wlr_math_token\" value=\"6c534f833bb3b46571cd712941ce3196\">\r\n            <\/div>\r\n        <!-- Bouton d'envoi -->\r\n                <div class=\"wlr-cf-field wlr-cf-submit-wrap\">\r\n            <button type=\"submit\" class=\"wlr-cf-submit\">\r\n                <span class=\"wlr-cf-btn-label\">Enviar<\/span>\r\n                <span class=\"wlr-cf-btn-spinner\" aria-hidden=\"true\" style=\"display:none;\"><\/span>\r\n            <\/button>\r\n        <\/div>\r\n\r\n    <\/form>\r\n\r\n    <!-- Mention RGPD -->\r\n    <p class=\"wlr-cf-rgpd-notice\">\r\n                Os dados coletados s\u00e3o usados exclusivamente para processar sua solicita\u00e7\u00e3o. Consulte nossa        <a href=\"https:\/\/themedicaltribune.com\/pt\/privacy-policy\" target=\"_blank\" rel=\"noopener\">pol\u00edtica de privacidade<\/a>.\r\n    <\/p>\r\n\r\n<\/div><!-- .wlr-cf-wrapper -->\r\n        \n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sponsoring Version de r\u00e9f\u00e9rence : Fran\u00e7aise (FR) Derni\u00e8re mise \u00e0 jour : 02\/02\/2026 Conform\u00e9ment \u00e0 l&#8217;article 20 de la LCEN (loi n\u00b0 2004-575 du 21 juin 2004), au Code de la consommation, aux recommandations de l&#8217;ARPP (Autorit\u00e9 de R\u00e9gulation Professionnelle de la Publicit\u00e9) et \u00e0 la Charte de d\u00e9ontologie de la presse en ligne, toute&hellip; <a class=\"more-link\" href=\"https:\/\/themedicaltribune.com\/pt\/sponsoring\/\">Continuar lendo <span class=\"screen-reader-text\">Sponsoring<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":0,"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"wp:attachment":[{"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}