{"id":13,"date":"2026-02-23T19:52:44","date_gmt":"2026-02-23T18:52:44","guid":{"rendered":"https:\/\/themedicaltribune.com\/pt\/dpo\/"},"modified":"2026-02-23T19:52:44","modified_gmt":"2026-02-23T18:52:44","slug":"dpo","status":"publish","type":"page","link":"https:\/\/themedicaltribune.com\/pt\/dpo\/","title":{"rendered":"DPO"},"content":{"rendered":"<div class=\"newsletter-section\">\n<div class=\"wlr-cf-wrapper wlr-cf-dpo\"\r\n          data-form-type=\"dpo\"\r\n     data-lang=\"pt\">\r\n\r\n    <!-- Message de retour (succ\u00e8s \/ erreur) -->\r\n    <div class=\"wlr-cf-response\" role=\"alert\" aria-live=\"polite\" aria-atomic=\"true\" style=\"display:none;\"><\/div>\r\n\r\n    <form\r\n        class=\"wlr-cf-form\"\r\n        id=\"wlr-form-dpo-245\"\r\n        method=\"post\"\r\n        action=\"https:\/\/themedicaltribune.com\/pt\/wp-admin\/admin-ajax.php\"\r\n        novalidate\r\n        autocomplete=\"on\"\r\n    >\r\n        <!-- Champs cach\u00e9s obligatoires -->\r\n        <input type=\"hidden\" name=\"action\"    value=\"wlr_cf_submit\">\r\n        <input type=\"hidden\" name=\"form_type\" value=\"dpo\">\r\n        <input type=\"hidden\" name=\"wlr_cf_nonce\" id=\"wlr-form-dpo-245_nonce\"\r\n               value=\"eea40efe92\">\r\n\r\n        <div class=\"wlr-cf-hp\" aria-hidden=\"true\" tabindex=\"-1\" style=\"position:absolute;left:-9999px;width:1px;height:1px;overflow:hidden;\"><label for=\"wlr_ebab7969\">Ne pas remplir<\/label><input type=\"text\" id=\"wlr_ebab7969\" name=\"wlr_ebab7969\" value=\"\" autocomplete=\"off\" tabindex=\"-1\"><\/div><div class=\"wlr-cf-field wlr-cf-field--text\" data-field=\"nom\"><label for=\"wlr-form-dpo-245_nom\">Nome completo <span class=\"wlr-cf-required\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wlr-form-dpo-245_nom\" name=\"nom\" placeholder=\"Seu nome e sobrenome\" autocomplete=\"off\" required aria-required=\"true\" class=\"wlr-cf-input\"><span class=\"wlr-cf-field-error\" role=\"alert\" aria-live=\"polite\"><\/span><\/div><div class=\"wlr-cf-field wlr-cf-field--email\" data-field=\"email\"><label for=\"wlr-form-dpo-245_email\">Endere\u00e7o de e-mail <span class=\"wlr-cf-required\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wlr-form-dpo-245_email\" name=\"email\" placeholder=\"voce@email.com\" autocomplete=\"email\" required aria-required=\"true\" class=\"wlr-cf-input\"><span class=\"wlr-cf-field-error\" role=\"alert\" aria-live=\"polite\"><\/span><\/div><div class=\"wlr-cf-field wlr-cf-field--text\" data-field=\"nature_demande\"><label for=\"wlr-form-dpo-245_nature_demande\">Tipo de solicita\u00e7\u00e3o <span class=\"wlr-cf-required\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wlr-form-dpo-245_nature_demande\" name=\"nature_demande\" placeholder=\"Ex. acesso ou retifica\u00e7\u00e3o ou exclus\u00e3o\" autocomplete=\"off\" required aria-required=\"true\" class=\"wlr-cf-input\"><span class=\"wlr-cf-field-error\" role=\"alert\" aria-live=\"polite\"><\/span><\/div><div class=\"wlr-cf-field wlr-cf-field--text\" data-field=\"sujet\"><label for=\"wlr-form-dpo-245_sujet\">Assunto <span class=\"wlr-cf-required\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wlr-form-dpo-245_sujet\" name=\"sujet\" placeholder=\"Breve descri\u00e7\u00e3o da sua solicita\u00e7\u00e3o\" autocomplete=\"off\" required aria-required=\"true\" class=\"wlr-cf-input\"><span class=\"wlr-cf-field-error\" role=\"alert\" aria-live=\"polite\"><\/span><\/div><div class=\"wlr-cf-field wlr-cf-field--textarea\" data-field=\"message\"><label for=\"wlr-form-dpo-245_message\">Mensagem <span class=\"wlr-cf-required\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wlr-form-dpo-245_message\" name=\"message\" placeholder=\"Escreva sua mensagem aqui\u2026\" rows=\"5\" required aria-required=\"true\" class=\"wlr-cf-input wlr-cf-textarea\"><\/textarea><small class=\"wlr-cf-help\">De acordo com o RGPD voc\u00ea pode exercer seus direitos entrando em contato conosco.<\/small><span class=\"wlr-cf-field-error\" role=\"alert\" aria-live=\"polite\"><\/span><\/div><div class=\"wlr-cf-math-challenge\">\r\n                <label for=\"wlr_math_answer\">Verifica\u00e7\u00e3o: <strong>6 + 1 = ?<\/strong><\/label>\r\n                <input type=\"number\" id=\"wlr_math_answer\" name=\"wlr_math_answer\"\r\n                       min=\"1\" max=\"18\" required autocomplete=\"off\"\r\n                       placeholder=\"Sua resposta\" aria-required=\"true\">\r\n                <input type=\"hidden\" name=\"wlr_math_token\" value=\"b0256f481f9fc6a91cc06ae7a0fffac9\">\r\n            <\/div>\r\n        <!-- Bouton d'envoi -->\r\n                <div class=\"wlr-cf-field wlr-cf-submit-wrap\">\r\n            <button type=\"submit\" class=\"wlr-cf-submit\">\r\n                <span class=\"wlr-cf-btn-label\">Enviar<\/span>\r\n                <span class=\"wlr-cf-btn-spinner\" aria-hidden=\"true\" style=\"display:none;\"><\/span>\r\n            <\/button>\r\n        <\/div>\r\n\r\n    <\/form>\r\n\r\n    <!-- Mention RGPD -->\r\n    <p class=\"wlr-cf-rgpd-notice\">\r\n                Os dados coletados s\u00e3o usados exclusivamente para processar sua solicita\u00e7\u00e3o. Consulte nossa        <a href=\"https:\/\/themedicaltribune.com\/pt\/privacy-policy\" target=\"_blank\" rel=\"noopener\">pol\u00edtica de privacidade<\/a>.\r\n    <\/p>\r\n\r\n<\/div><!-- .wlr-cf-wrapper -->\r\n        \n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/pages\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":0,"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/pages\/13\/revisions"}],"wp:attachment":[{"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/media?parent=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}