{"id":34,"date":"2026-06-19T01:53:21","date_gmt":"2026-06-18T23:53:21","guid":{"rendered":"https:\/\/themedicaltribune.com\/pt\/2026\/06\/19\/o-calor-agrava-as-doencas-respiratorias\/"},"modified":"2026-06-19T01:54:49","modified_gmt":"2026-06-18T23:54:49","slug":"o-calor-agrava-as-doencas-respiratorias","status":"publish","type":"post","link":"https:\/\/themedicaltribune.com\/pt\/2026\/06\/19\/o-calor-agrava-as-doencas-respiratorias\/","title":{"rendered":"O calor agrava as doen\u00e7as respirat\u00f3rias"},"content":{"rendered":"<p>&#8220;`html<\/p>\n<h1>O calor agrava as doen\u00e7as respirat\u00f3rias<\/h1>\n<p>As doen\u00e7as respirat\u00f3rias representam um grande desafio de sa\u00fade p\u00fablica em todo o mundo. Com o aquecimento global, os epis\u00f3dios de calor est\u00e3o se tornando mais frequentes e intensos, o que levanta quest\u00f5es sobre seus efeitos na sa\u00fade respirat\u00f3ria. Um estudo realizado na Coreia do Sul entre 2014 e 2019 analisou os v\u00ednculos entre as temperaturas elevadas e as visitas \u00e0 emerg\u00eancia por problemas respirat\u00f3rios em 16 regi\u00f5es do pa\u00eds durante a esta\u00e7\u00e3o quente, de abril a setembro.<\/p>\n<p>Os resultados mostram que um aumento de um grau Celsius na temperatura m\u00e1xima di\u00e1ria leva a um aumento significativo nas visitas \u00e0 emerg\u00eancia para todas as doen\u00e7as respirat\u00f3rias. Esse aumento \u00e9 particularmente marcado para afec\u00e7\u00f5es como pneumonia, doen\u00e7a pulmonar obstrutiva cr\u00f4nica, asma e infec\u00e7\u00f5es das vias respirat\u00f3rias superiores. Homens, crian\u00e7as com menos de 15 anos e pessoas com 65 anos ou mais s\u00e3o os mais afetados.<\/p>\n<p>A doen\u00e7a pulmonar obstrutiva cr\u00f4nica \u00e9 uma doen\u00e7a pulmonar de longo prazo que obstrui as vias respirat\u00f3rias e dificulta a respira\u00e7\u00e3o. As infec\u00e7\u00f5es das vias respirat\u00f3rias superiores, por sua vez, afetam o nariz, a garganta e as vias respirat\u00f3rias superiores, causando sintomas como tosse ou dor de garganta.<\/p>\n<p>O estudo tamb\u00e9m revelou que o impacto das temperaturas elevadas na sa\u00fade respirat\u00f3ria persiste mesmo ap\u00f3s a considera\u00e7\u00e3o de fatores como umidade, dia da semana ou polui\u00e7\u00e3o atmosf\u00e9rica. Isso sugere que o calor em si desempenha um papel direto na piora dessas doen\u00e7as. Os mecanismos exatos ainda s\u00e3o parcialmente incompreendidos, mas v\u00e1rias hip\u00f3teses existem. As temperaturas elevadas favorecem a forma\u00e7\u00e3o de poluentes atmosf\u00e9ricos como o oz\u00f4nio, que irritam as vias respirat\u00f3rias e agravam os sintomas. Al\u00e9m disso, o calor pode enfraquecer o sistema imunol\u00f3gico, tornando os indiv\u00edduos mais vulner\u00e1veis a infec\u00e7\u00f5es.<\/p>\n<p>As diferen\u00e7as observadas de acordo com a idade e o sexo s\u00e3o not\u00e1veis. Os homens parecem mais sens\u00edveis \u00e0 asma e \u00e0 doen\u00e7a pulmonar obstrutiva cr\u00f4nica do que as mulheres. Em crian\u00e7as, as infec\u00e7\u00f5es respirat\u00f3rias agudas s\u00e3o mais frequentes com o aumento das temperaturas, enquanto os idosos s\u00e3o mais afetados pela doen\u00e7a pulmonar obstrutiva cr\u00f4nica. Essas varia\u00e7\u00f5es poderiam ser explicadas por diferen\u00e7as fisiol\u00f3gicas, como uma pior regula\u00e7\u00e3o da temperatura corporal em crian\u00e7as pequenas e idosos, ou por fatores sociais, como h\u00e1bitos de vida ou exposi\u00e7\u00e3o ao calor.<\/p>\n<p>Os resultados deste estudo destacam a import\u00e2ncia de implementar pol\u00edticas de preven\u00e7\u00e3o direcionadas para proteger as popula\u00e7\u00f5es vulner\u00e1veis durante as ondas de calor. Isso poderia incluir sistemas de alerta precoce, um melhor planejamento dos recursos m\u00e9dicos e campanhas de conscientiza\u00e7\u00e3o para limitar a exposi\u00e7\u00e3o ao calor. Com a mudan\u00e7a clim\u00e1tica, essas medidas se tornam essenciais para reduzir o impacto das temperaturas extremas na sa\u00fade respirat\u00f3ria.<\/p>\n<p>&#8220;`<\/p>\n<hr>\n<h2>Sources utilis\u00e9es<\/h2>\n<h3>Source du rapport<\/h3>\n<p><strong>DOI\u00a0:<\/strong> <a href=\"https:\/\/doi.org\/10.1007\/s00484-026-03242-0\" target=\"_blank\">https:\/\/doi.org\/10.1007\/s00484-026-03242-0<\/a><\/p>\n<p><strong>Titre\u00a0:<\/strong> Impact of heat on respiratory health: Age- and sex-specific risks in a nationwide Korean study (2014\u20132019)<\/p>\n<p><strong>Revue : <\/strong> International Journal of Biometeorology<\/p>\n<p><strong>\u00c9diteur : <\/strong> Springer Science and Business Media LLC<\/p>\n<p><strong>Auteurs : <\/strong> Joonho Ahn; Jongmin Oh; Ho-Jang Kwon; Hyungryul Lim; Jonghyuk Choi; Sanghyuk Bae; Kyoung-Nam Kim; Mi-Ji Kim; Jong-Hun Kim; Youn-Hee Lim<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;`html O calor agrava as doen\u00e7as respirat\u00f3rias As doen\u00e7as respirat\u00f3rias representam um grande desafio de sa\u00fade p\u00fablica em todo o mundo. Com o aquecimento global, os epis\u00f3dios de calor est\u00e3o se tornando mais frequentes e intensos, o que levanta quest\u00f5es sobre seus efeitos na sa\u00fade respirat\u00f3ria. Um estudo realizado na Coreia do Sul entre 2014&hellip; <a class=\"more-link\" href=\"https:\/\/themedicaltribune.com\/pt\/2026\/06\/19\/o-calor-agrava-as-doencas-respiratorias\/\">Continuar lendo <span class=\"screen-reader-text\">O calor agrava as doen\u00e7as respirat\u00f3rias<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,7,2],"tags":[],"class_list":["post-34","post","type-post","status-publish","format-standard","hentry","category-internacional","category-meio-ambiente","category-saude","entry"],"_links":{"self":[{"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/posts\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/comments?post=34"}],"version-history":[{"count":1,"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/posts\/34\/revisions"}],"predecessor-version":[{"id":35,"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/posts\/34\/revisions\/35"}],"wp:attachment":[{"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/media?parent=34"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/categories?post=34"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/themedicaltribune.com\/pt\/wp-json\/wp\/v2\/tags?post=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}